{"id":55949,"date":"2021-06-15T08:29:51","date_gmt":"2021-06-15T08:29:51","guid":{"rendered":"https:\/\/manezylozano.com\/?p=55949"},"modified":"2021-06-15T10:53:40","modified_gmt":"2021-06-15T10:53:40","slug":"plan-renove-maquinaria-atomizadores-2021","status":"publish","type":"post","link":"https:\/\/manezylozano.com\/fr\/plan-renove-maquinaria-atomizadores-2021\/","title":{"rendered":"Plan Renove Maquinaria Agr\u00edcola 2021"},"content":{"rendered":"<div class=\"wpb-content-wrapper\" id=\"wpb-content-root\"><p>[vc_row][vc_column][vc_column_text]<span style=\"font-size: 21px;\"><b>Plan Renove 2021 maquinaria agr\u00edcola<\/b><\/span><!--more--><\/p>\n<p>El Ministerio de Agricultura, Pesca y Alimentaci\u00f3n ha publicado en el Bolet\u00edn Oficial del Estado, la convocatoria de ayudas para la renovaci\u00f3n del parque nacional de maquinaria agr\u00edcola correspondiente a 2021.<\/p>\n<p>Dotado con un presupuesto de<strong> 6,5 millones de euros <\/strong>que se distribuir\u00e1n mediante<strong> ayudas directas al agricultor.<\/strong><\/p>\n<p>Desde el d\u00eda 15 de junio, y hasta el 15 de septiembre, se pueden solicitar las<strong> ayudas<\/strong> del <strong>Plan Renove de maquinaria agr\u00edcola 2021<\/strong>, convocadas por el Ministerio de Agricultura, Pesca y Alimentaci\u00f3n. De esta forma el solicitante dispondr\u00e1 de cinco meses para comprar la nueva m\u00e1quina, realizar su inscripci\u00f3n en el Registro Oficial de Maquinaria Agr\u00edcola y tramitar la solicitud.<\/p>\n<p>&nbsp;<\/p>\n<p>Se atienden as\u00ed las diversas necesidades de mecanizaci\u00f3n de la agricultura espa\u00f1ola, incorporando m\u00e1quinas m\u00e1s eficientes, con mayor capacidad de trabajo, m\u00e1s seguras y m\u00e1s respetuosas con el medio ambiente, con la clara orientaci\u00f3n europea hacia una <strong>agricultura sostenible y m\u00e1s respetuosa con el medio ambiente<\/strong>, que implica la necesidad de remodelar el sector agr\u00edcola espa\u00f1ol, incentivando modelos de producci\u00f3n menos contaminantes.<\/p>\n<p>Todo ello refuerza la importancia de\u00a0<strong>renovar el actual parqu\u00e9 de maquinaria agr\u00edcola<\/strong>\u00a0para lograr una mayor productividad del campo contaminando menos.<\/p>\n<p>&nbsp;<\/p>\n<p>La ayuda para la compra de <strong>equipos de aplicaci\u00f3n de productos fitosanitarios<\/strong> se establece en el <strong>30% de la inversi\u00f3n<\/strong> sin IVA y no podr\u00e1 superar los 6.000 euros.<\/p>\n<p>Las ayudas se conceder\u00e1n por riguroso orden de presentaci\u00f3n de las solicitudes a trav\u00e9s del enlace correspondiente en la p\u00e1gina web del Ministerio de Agricultura y Pesca, Alimentaci\u00f3n y Medio Ambiente, hasta el agotamiento de los fondos disponibles.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>La maquinaria substituida deber\u00e1 cumplir los siguientes requisitos, en el caso de la adquisici\u00f3n de un atomizador,:<\/strong><\/p>\n<ul>\n<li>Atomizador arrastrado o suspendido a veh\u00edculo tractor, de aplicaci\u00f3n de productos fitosanitarios, del mismo tipo que la adquirida.<\/li>\n<li>Estar en condiciones de uso y no de abandono. Se admitir\u00e1 que la ITV est\u00e9 caducada durante un per\u00edodo inferior o igual a un a\u00f1o respecto de la fecha de solicitud de la subvenci\u00f3n.<\/li>\n<li>Entregar el atomizador viejo en un centro autorizado y obtener certificado de achatarramiento.<\/li>\n<li>La antig\u00fcedad de la inscripci\u00f3n en el ROMA, debe ser al menos, desde el 1 de enero de 2016 a nombre del solicitante de la ayuda.<\/li>\n<li>Deber\u00e1 haberse solicitado la correspondiente baja en el ROMA.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p>Las subvenciones deben tramitarse a trav\u00e9s de la p\u00e1gina web del MAPA, con el formulario electr\u00f3nico que se habilitar\u00e1 en la misma, acompa\u00f1ada de toda la documentaci\u00f3n pertinente: acreditaci\u00f3n del beneficiario, facturas de compra, certificados de la maquinaria adquirida y de la titularidad de la misma, ficha t\u00e9cnica, informe de la ITV si procede y compromiso de destrucci\u00f3n y baja del ROMA de la m\u00e1quina a sustituir.<\/p>\n<p>&nbsp;<\/p>\n<p>Puedes consultar toda la informaci\u00f3n detallada en:<\/p>\n<p><a href=\"https:\/\/www.mapa.gob.es\/es\/agricultura\/temas\/medios-de-produccion\/maquinaria-agricola\/ayudas\/ayudas_renovacion_de_maquinaria\/\" target=\"_blank\" rel=\"noopener noreferrer\">Convocatoria Plan Renove 2021<\/a><\/p>\n<p><a href=\"https:\/\/www.mapa.gob.es\/es\/agricultura\/temas\/medios-de-produccion\/textoconsolidadord704-2017_tcm30-539664.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Real Decreto 704\/2017<\/a><\/p>\n<p><a class=\"\" href=\"https:\/\/www.mapa.gob.es\/es\/agricultura\/temas\/medios-de-produccion\/realdecreto294-2018modificard704-2017_tcm30-452750.pdf\" target=\"_blank\" rel=\"noopener noreferrer\">Real Decreto 294\/2018, por el que se modifica el Real Decreto 704\/2017<\/a><\/p>\n<p><a class=\"\" href=\"https:\/\/gestionrenove.es\/SGP_Renove\/\" target=\"_blank\" rel=\"noopener noreferrer\">Acceso a la aplicaci\u00f3n para gestionar la solicitud<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>CONTACTA CON NOSOTROS -&gt; <a href=\"https:\/\/manezylozano.com\/contacto-fabricantes-atomizadores-valencia\/\" target=\"_blank\" rel=\"noopener noreferrer\">CLICK AQU\u00cd<\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>[\/vc_column_text][vc_single_image image=\u00a0\u00bb55951&Prime; img_size=\u00a0\u00bblarge\u00a0\u00bb alignment=\u00a0\u00bbcenter\u00a0\u00bb][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text]Plan Renove 2021 maquinaria agr\u00edcola<\/p>\n","protected":false},"author":1,"featured_media":55951,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_monsterinsights_skip_tracking":false,"footnotes":""},"categories":[105],"tags":[],"class_list":["post-55949","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-productos","category-105","description-off"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Plan Renove Maquinaria Agr\u00edcola 2021 | Ma\u00f1ez y Lozano Twister Sprayers<\/title>\n<meta name=\"description\" content=\"Plan Renove Maquinaria Agr\u00edcola 2021. Cambia tu atomizador por uno nuevo. Subvenci\u00f3n Ministerio Agricultura 30% Atomizadores Ma\u00f1ez Lozano\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Plan Renove Maquinaria Agr\u00edcola 2021 | Ma\u00f1ez y Lozano Twister Sprayers\" \/>\n<meta property=\"og:description\" content=\"Plan Renove Maquinaria Agr\u00edcola 2021. Cambia tu atomizador por uno nuevo. Subvenci\u00f3n Ministerio Agricultura 30% Atomizadores Ma\u00f1ez Lozano\" \/>\n<meta property=\"og:url\" content=\"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Ma\u00f1ez y Lozano\" \/>\n<meta property=\"article:published_time\" content=\"2021-06-15T08:29:51+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-06-15T10:53:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/manezylozano.com\/wp-content\/uploads\/2021\/06\/plan-renove-maquinaria-fitosanitarios-ma\u00f1ez-lozano.png\" \/>\n\t<meta property=\"og:image:width\" content=\"940\" \/>\n\t<meta property=\"og:image:height\" content=\"788\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"manezylozano\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"manezylozano\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/manezylozano.com\\\/plan-renove-maquinaria-atomizadores-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manezylozano.com\\\/plan-renove-maquinaria-atomizadores-2021\\\/\"},\"author\":{\"name\":\"manezylozano\",\"@id\":\"https:\\\/\\\/manezylozano.com\\\/#\\\/schema\\\/person\\\/eeca32cc201f5170dd410aa911b59300\"},\"headline\":\"Plan Renove Maquinaria Agr\u00edcola 2021\",\"datePublished\":\"2021-06-15T08:29:51+00:00\",\"dateModified\":\"2021-06-15T10:53:40+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/manezylozano.com\\\/plan-renove-maquinaria-atomizadores-2021\\\/\"},\"wordCount\":562,\"publisher\":{\"@id\":\"https:\\\/\\\/manezylozano.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/manezylozano.com\\\/plan-renove-maquinaria-atomizadores-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manezylozano.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/plan-renove-maquinaria-fitosanitarios-ma\u00f1ez-lozano.png\",\"articleSection\":[\"Productos\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/manezylozano.com\\\/plan-renove-maquinaria-atomizadores-2021\\\/\",\"url\":\"https:\\\/\\\/manezylozano.com\\\/plan-renove-maquinaria-atomizadores-2021\\\/\",\"name\":\"Plan Renove Maquinaria Agr\u00edcola 2021 | Ma\u00f1ez y Lozano Twister Sprayers\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/manezylozano.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/manezylozano.com\\\/plan-renove-maquinaria-atomizadores-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/manezylozano.com\\\/plan-renove-maquinaria-atomizadores-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/manezylozano.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/plan-renove-maquinaria-fitosanitarios-ma\u00f1ez-lozano.png\",\"datePublished\":\"2021-06-15T08:29:51+00:00\",\"dateModified\":\"2021-06-15T10:53:40+00:00\",\"description\":\"Plan Renove Maquinaria Agr\u00edcola 2021. Cambia tu atomizador por uno nuevo. Subvenci\u00f3n Ministerio Agricultura 30% Atomizadores Ma\u00f1ez Lozano\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/manezylozano.com\\\/plan-renove-maquinaria-atomizadores-2021\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/manezylozano.com\\\/plan-renove-maquinaria-atomizadores-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/manezylozano.com\\\/plan-renove-maquinaria-atomizadores-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/manezylozano.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/plan-renove-maquinaria-fitosanitarios-ma\u00f1ez-lozano.png\",\"contentUrl\":\"https:\\\/\\\/manezylozano.com\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/plan-renove-maquinaria-fitosanitarios-ma\u00f1ez-lozano.png\",\"width\":940,\"height\":788},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/manezylozano.com\\\/plan-renove-maquinaria-atomizadores-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/manezylozano.com\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Plan Renove Maquinaria Agr\u00edcola 2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/manezylozano.com\\\/#website\",\"url\":\"https:\\\/\\\/manezylozano.com\\\/\",\"name\":\"Ma\u00f1ez y Lozano\",\"description\":\"Atomizadores\",\"publisher\":{\"@id\":\"https:\\\/\\\/manezylozano.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/manezylozano.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/manezylozano.com\\\/#organization\",\"name\":\"Ma\u00f1ez y Lozano\",\"url\":\"https:\\\/\\\/manezylozano.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/manezylozano.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/manezylozano.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/3CC1936C-CABB-494E-A4AF-4F29BCB3D712.png\",\"contentUrl\":\"https:\\\/\\\/manezylozano.com\\\/wp-content\\\/uploads\\\/2018\\\/03\\\/3CC1936C-CABB-494E-A4AF-4F29BCB3D712.png\",\"width\":200,\"height\":101,\"caption\":\"Ma\u00f1ez y Lozano\"},\"image\":{\"@id\":\"https:\\\/\\\/manezylozano.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/manezylozano.com\\\/#\\\/schema\\\/person\\\/eeca32cc201f5170dd410aa911b59300\",\"name\":\"manezylozano\",\"url\":\"https:\\\/\\\/manezylozano.com\\\/fr\\\/author\\\/manezylozano\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Plan Renove Maquinaria Agr\u00edcola 2021 | Ma\u00f1ez y Lozano Twister Sprayers","description":"Plan Renove Maquinaria Agr\u00edcola 2021. Cambia tu atomizador por uno nuevo. Subvenci\u00f3n Ministerio Agricultura 30% Atomizadores Ma\u00f1ez Lozano","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/","og_locale":"fr_FR","og_type":"article","og_title":"Plan Renove Maquinaria Agr\u00edcola 2021 | Ma\u00f1ez y Lozano Twister Sprayers","og_description":"Plan Renove Maquinaria Agr\u00edcola 2021. Cambia tu atomizador por uno nuevo. Subvenci\u00f3n Ministerio Agricultura 30% Atomizadores Ma\u00f1ez Lozano","og_url":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/","og_site_name":"Ma\u00f1ez y Lozano","article_published_time":"2021-06-15T08:29:51+00:00","article_modified_time":"2021-06-15T10:53:40+00:00","og_image":[{"width":940,"height":788,"url":"https:\/\/manezylozano.com\/wp-content\/uploads\/2021\/06\/plan-renove-maquinaria-fitosanitarios-ma\u00f1ez-lozano.png","type":"image\/png"}],"author":"manezylozano","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"manezylozano","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/#article","isPartOf":{"@id":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/"},"author":{"name":"manezylozano","@id":"https:\/\/manezylozano.com\/#\/schema\/person\/eeca32cc201f5170dd410aa911b59300"},"headline":"Plan Renove Maquinaria Agr\u00edcola 2021","datePublished":"2021-06-15T08:29:51+00:00","dateModified":"2021-06-15T10:53:40+00:00","mainEntityOfPage":{"@id":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/"},"wordCount":562,"publisher":{"@id":"https:\/\/manezylozano.com\/#organization"},"image":{"@id":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/manezylozano.com\/wp-content\/uploads\/2021\/06\/plan-renove-maquinaria-fitosanitarios-ma\u00f1ez-lozano.png","articleSection":["Productos"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/","url":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/","name":"Plan Renove Maquinaria Agr\u00edcola 2021 | Ma\u00f1ez y Lozano Twister Sprayers","isPartOf":{"@id":"https:\/\/manezylozano.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/#primaryimage"},"image":{"@id":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/manezylozano.com\/wp-content\/uploads\/2021\/06\/plan-renove-maquinaria-fitosanitarios-ma\u00f1ez-lozano.png","datePublished":"2021-06-15T08:29:51+00:00","dateModified":"2021-06-15T10:53:40+00:00","description":"Plan Renove Maquinaria Agr\u00edcola 2021. Cambia tu atomizador por uno nuevo. Subvenci\u00f3n Ministerio Agricultura 30% Atomizadores Ma\u00f1ez Lozano","breadcrumb":{"@id":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/#primaryimage","url":"https:\/\/manezylozano.com\/wp-content\/uploads\/2021\/06\/plan-renove-maquinaria-fitosanitarios-ma\u00f1ez-lozano.png","contentUrl":"https:\/\/manezylozano.com\/wp-content\/uploads\/2021\/06\/plan-renove-maquinaria-fitosanitarios-ma\u00f1ez-lozano.png","width":940,"height":788},{"@type":"BreadcrumbList","@id":"https:\/\/manezylozano.com\/plan-renove-maquinaria-atomizadores-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/manezylozano.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Plan Renove Maquinaria Agr\u00edcola 2021"}]},{"@type":"WebSite","@id":"https:\/\/manezylozano.com\/#website","url":"https:\/\/manezylozano.com\/","name":"Ma\u00f1ez y Lozano","description":"Atomizadores","publisher":{"@id":"https:\/\/manezylozano.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/manezylozano.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/manezylozano.com\/#organization","name":"Ma\u00f1ez y Lozano","url":"https:\/\/manezylozano.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/manezylozano.com\/#\/schema\/logo\/image\/","url":"https:\/\/manezylozano.com\/wp-content\/uploads\/2018\/03\/3CC1936C-CABB-494E-A4AF-4F29BCB3D712.png","contentUrl":"https:\/\/manezylozano.com\/wp-content\/uploads\/2018\/03\/3CC1936C-CABB-494E-A4AF-4F29BCB3D712.png","width":200,"height":101,"caption":"Ma\u00f1ez y Lozano"},"image":{"@id":"https:\/\/manezylozano.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/manezylozano.com\/#\/schema\/person\/eeca32cc201f5170dd410aa911b59300","name":"manezylozano","url":"https:\/\/manezylozano.com\/fr\/author\/manezylozano\/"}]}},"_links":{"self":[{"href":"https:\/\/manezylozano.com\/fr\/wp-json\/wp\/v2\/posts\/55949","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/manezylozano.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/manezylozano.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/manezylozano.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/manezylozano.com\/fr\/wp-json\/wp\/v2\/comments?post=55949"}],"version-history":[{"count":0,"href":"https:\/\/manezylozano.com\/fr\/wp-json\/wp\/v2\/posts\/55949\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/manezylozano.com\/fr\/wp-json\/wp\/v2\/media\/55951"}],"wp:attachment":[{"href":"https:\/\/manezylozano.com\/fr\/wp-json\/wp\/v2\/media?parent=55949"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/manezylozano.com\/fr\/wp-json\/wp\/v2\/categories?post=55949"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/manezylozano.com\/fr\/wp-json\/wp\/v2\/tags?post=55949"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}